{"id":33338,"date":"2025-12-12T16:36:24","date_gmt":"2025-12-12T14:36:24","guid":{"rendered":"https:\/\/tdcenter.org\/?p=33338"},"modified":"2026-07-04T12:02:02","modified_gmt":"2026-07-04T09:02:02","slug":"a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc","status":"publish","type":"post","link":"https:\/\/tdcenter.org\/it\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/","title":{"rendered":"Una nuova generazione di voci regionali: gli studenti latinoamericani concludono il loro tirocinio presso il TDC"},"content":{"rendered":"<p class=\"wp-block-paragraph translation-block\">Da agosto a dicembre 2025, il<strong>Centro per il Dialogo Transatlantico ha ospitato<\/strong> <strong>un<\/strong> <strong>tirocinio a distanza per otto studenti provenienti da Argentina, Cile e Per\u00f9<\/strong>nell'ambito del Programma di cooperazione Spagna e America Latina. I partecipanti rappresentavano un gruppo eterogeneo di istituzioni, tra cui<em>Universidad Argentina de la Empresa<\/em>, <em>Universidad Cat\u00f3lica de Santiago del Estero,<\/em> <em>Universidad del CEMA<\/em>, e<em>Universidad del Salvador<\/em>in Argentina;<em>Universidad de Concepci\u00f3n<\/em>e<em>Universidad Diego Portales<\/em>in Cile; e<em>Universidad Nacional Pedro Ruiz Gallo<\/em>in Per\u00f9. L'obiettivo del programma era offrire a giovani ricercatori un'esperienza pratica nel lavoro analitico, negli studi sui media e nella comunicazione strategica nel campo degli affari internazionali.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design-1024x576.png\" alt=\"\" class=\"wp-image-33340\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design-1024x576.png 1024w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design-600x338.png 600w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design-768x432.png 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design-1536x864.png 1536w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design-18x10.png 18w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Il progetto centrale del tirocinio \u00e8 stato uno studio congiunto intitolato<em><strong>\u201cNarrazioni in competizione: come si informa e si disinforma sull\u2019Ucraina in America Latina\u201d<\/strong><\/em>. I tirocinanti hanno svolto diverse fasi di ricerca, a partire dalla raccolta di dati e dal monitoraggio dei media russi, ucraini e latinoamericani in lingua spagnola. Hanno analizzato temi predominanti, tono, inquadramento emotivo e schemi narrativi. Nelle fasi successive, hanno prodotto una valutazione preliminare e una matrice comparativa che esaminava differenze e somiglianze tra le fonti, inclusi presentazione visiva, carico emotivo e tecniche di manipolazione. La fase finale ha previsto sondaggi e verifiche sul campo per comprendere come il pubblico in Argentina, Cile e Per\u00f9 percepisca e interiorizzi queste narrazioni. Lo studio \u00e8<a href=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/TDC_Narrativas_en_disputa_Handbook.pdf\" target=\"_self\">disponibile al<\/a><a href=\"https:\/\/tdcenter.org\/es\/2025\/12\/12\/narrativas-en-disputa-como-se-informa-y-se-desinforma-sobre-ucrania-en-america-latina\/\" target=\"_self\"> <\/a><a href=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/TDC_Narrativas_en_disputa_Handbook.pdf\" target=\"_self\">link<\/a>indicato.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/TDC_Narrativas_en_disputa_Handbook.pdf\"><img decoding=\"async\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/tg_image_729326012-721x1024.jpeg\" alt=\"Cover image for: Narrativas en disputa: \u00bfC\u00f3mo se informa (y se desinforma) sobre Ucrania en Am\u00e9rica Latina?\" class=\"wp-image-33348\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/TDC_Narrativas_en_disputa_Handbook.pdf\"><img decoding=\"async\" width=\"722\" height=\"1024\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/tg_image_2005113580-722x1024.jpeg\" alt=\"\" class=\"wp-image-33351\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/tg_image_2005113580-722x1024.jpeg 722w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/tg_image_2005113580-423x600.jpeg 423w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/tg_image_2005113580-768x1089.jpeg 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/tg_image_2005113580-1083x1536.jpeg 1083w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/tg_image_2005113580-8x12.jpeg 8w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/tg_image_2005113580.jpeg 1319w\" sizes=\"(max-width: 722px) 100vw, 722px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2026\/01\/TDC_Narrativas_en_disputaHandbook.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporamento di TDC_Narrativas_en_disputa(Handbook).\"><\/object><a id=\"wp-block-file--media-593657c8-c94b-4ba4-bc3c-f94dfe2cdc81\" href=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2026\/01\/TDC_Narrativas_en_disputaHandbook.pdf\">TDC_Narrativas_en_disputa(Handbook)<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Oltre al lavoro analitico, i tirocinanti hanno contribuito alle attivit\u00e0 di comunicazione del TDC, documentando il percorso di tirocinio e producendo brevi video per i social media. Hanno inoltre contribuito alla revisione delle versioni in lingua spagnola di due importanti studi analitici del TDC,<em> <\/em><strong><em>\u201cSAFE pu\u00f2 rendere l'Ucraina pi\u00f9 sicura? Approfondimenti sul nuovo strumento finanziario europeo\u201d<\/em><\/strong>e<strong><em>\u201cIl ruolo della Russia nell'ordine mondiale del dopoguerra. Come evolver\u00e0 la posizione della Russia nel Sud globale e nelle istituzioni internazionali?\u201d<\/em><\/strong>. Ci\u00f2 ha offerto ai partecipanti un'esperienza diretta nella scrittura orientata alle politiche pubbliche, negli standard metodologici e nell'adattamento di ricerche complesse per un pubblico di lingua spagnola.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"642\" height=\"1024\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4826-642x1024.jpg\" alt=\"\" class=\"wp-image-33341\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4826-642x1024.jpg 642w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4826-376x600.jpg 376w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4826-768x1226.jpg 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4826-963x1536.jpg 963w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4826-8x12.jpg 8w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4826.jpg 1170w\" sizes=\"(max-width: 642px) 100vw, 642px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"1024\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4825-600x1024.jpg\" alt=\"\" class=\"wp-image-33342\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4825-600x1024.jpg 600w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4825-352x600.jpg 352w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4825-768x1311.jpg 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4825-900x1536.jpg 900w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4825-7x12.jpg 7w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4825.jpg 1170w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"644\" height=\"1024\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4827-644x1024.jpg\" alt=\"\" class=\"wp-image-33343\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4827-644x1024.jpg 644w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4827-378x600.jpg 378w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4827-768x1220.jpg 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4827-967x1536.jpg 967w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4827-8x12.jpg 8w, https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/IMG_4827.jpg 1170w\" sizes=\"(max-width: 644px) 100vw, 644px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Il tirocinio si \u00e8 rivelato un'esperienza importante e formativa per i partecipanti. Per molti, \u00e8 stato il primo confronto strutturato con l'analisi comparativa dei media e la comunicazione internazionale. Come<strong>Ana Karla Bogoliuk<\/strong>, studentessa di Governo e Relazioni internazionali presso<em>Universidad Argentina de la Empresa<\/em>, ha osservato:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cQuesto tirocinio ha dato a tutti noi l'opportunit\u00e0 di approfondire la comprensione della comunicazione internazionale nel XXI secolo, della proliferazione di fake news e propaganda, della composizione dell'ambiente mediatico latinoamericano, delle abitudini informative e delle opinioni della popolazione, dell'individuazione delle narrazioni, nonch\u00e9 del caso oggetto di studio: la guerra tra Russia e Ucraina, i suoi antecedenti e la battaglia che si combatte anche nello spazio informativo\u201d.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Analogamente,<strong>Jes\u00fas Gonz\u00e1lez Parada<\/strong>, laureato in Scienze politiche e amministrative presso<em>Universidad de Concepci\u00f3n<\/em>, ha sottolineato la dimensione personale del programma:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cAl di l\u00e0 dei risultati accademici, questa esperienza \u00e8 stata profondamente arricchente sul piano personale. Mi ha permesso di generare nuove conoscenze, di sviluppare un pensiero critico sulla comunicazione internazionale, ma soprattutto di entrare in contatto con un team che, nel gergo cileno, pu\u00f2 essere definito \u2018bac\u00e1n\u2019: un team nel quale la distanza geografica \u00e8 scomparsa di fronte alla collaborazione, lasciando spazio a un senso di fraternit\u00e0 che trascende i confini\u201d.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Il programma ha mostrato come le prospettive latinoamericane arricchiscano la comprensione delle dinamiche informative globali. I partecipanti hanno applicato l'esperienza regionale in materia di frammentazione dei media, narrazioni di transizione e resilienza civica per interpretare come i messaggi concorrenti sull'Ucraina vengano costruiti e contestati nel mondo ispanofono. Il loro lavoro ha prodotto un quadro analitico strutturato che sosterr\u00e0 ricercatori, giornalisti e diplomatici in entrambe le regioni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\"><em>Questo progetto \u00e8 stato sostenuto dall'International Renaissance Foundation.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>From August to December 2025, the Transatlantic Dialogue Center hosted a remote internship for eight students from Argentina, Chile, and Peru through the Spain and Latin America Cooperation Program.&nbsp;Participants represented a diverse group of institutions, including Universidad Argentina de la Empresa, Universidad Cat\u00f3lica de Santiago del Estero, Universidad del CEMA, and Universidad del Salvador in [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":33340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,104],"tags":[],"topic":[],"class_list":["post-33338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events","category-spain-and-latin-america-cooperation-program-events"],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Latin American Students Complete Their Internship at TDC<\/title>\n<meta name=\"description\" content=\"Eight students from Argentina, Chile and Peru completed a remote TDC internship focused on regional perspectives and Ukraine\u2013Latin America relations.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tdcenter.org\/it\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Latin American Students Complete Their Internship at TDC\" \/>\n<meta property=\"og:description\" content=\"Eight students from Argentina, Chile and Peru completed a remote TDC internship focused on regional perspectives and Ukraine\u2013Latin America relations.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tdcenter.org\/it\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/\" \/>\n<meta property=\"og:site_name\" content=\"Transatlantic Dialogue Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Transatlantic-Dialogue-Center-105645698740463\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T14:36:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-04T09:02:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bohdana Batsko\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Latin American Students Complete Their Internship at TDC\" \/>\n<meta name=\"twitter:description\" content=\"Eight students from Argentina, Chile and Peru completed a remote TDC internship focused on regional perspectives and Ukraine\u2013Latin America relations.\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bohdana Batsko\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/\"},\"author\":{\"name\":\"Bohdana Batsko\",\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/person\/bfca4e53cbe272b2feb293444dfe9b55\"},\"headline\":\"A New Generation of Regional Voices: Latin American Students Complete Their Internship at TDC\",\"datePublished\":\"2025-12-12T14:36:24+00:00\",\"dateModified\":\"2026-07-04T09:02:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/\"},\"wordCount\":605,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/tdcenter.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png\",\"articleSection\":[\"Events\",\"Events-Spain and Latin America Cooperation Program\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/\",\"url\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/\",\"name\":\"Latin American Students Complete Their Internship at TDC\",\"isPartOf\":{\"@id\":\"https:\/\/tdcenter.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png\",\"datePublished\":\"2025-12-12T14:36:24+00:00\",\"dateModified\":\"2026-07-04T09:02:02+00:00\",\"description\":\"Eight students from Argentina, Chile and Peru completed a remote TDC internship focused on regional perspectives and Ukraine\u2013Latin America relations.\",\"breadcrumb\":{\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#primaryimage\",\"url\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png\",\"contentUrl\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tdcenter.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A New Generation of Regional Voices: Latin American Students Complete Their Internship at TDC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tdcenter.org\/#website\",\"url\":\"https:\/\/tdcenter.org\/\",\"name\":\"Transatlantic Dialogue Center\",\"description\":\"Promoting International Peace and Security\",\"publisher\":{\"@id\":\"https:\/\/tdcenter.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tdcenter.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tdcenter.org\/#organization\",\"name\":\"Transatlantic Dialogue Center\",\"url\":\"https:\/\/tdcenter.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2022\/04\/google.png\",\"contentUrl\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2022\/04\/google.png\",\"width\":2568,\"height\":2487,\"caption\":\"Transatlantic Dialogue Center\"},\"image\":{\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Transatlantic-Dialogue-Center-105645698740463\",\"https:\/\/www.youtube.com\/channel\/UCpJuhU4JBfpv_jsldNOc5LA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/person\/bfca4e53cbe272b2feb293444dfe9b55\",\"name\":\"Bohdana Batsko\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/tdcenter.org\/wp-content\/litespeed\/avatar\/d8f3b20c902e8bb3923b20886148cd59.jpg?ver=1788347320\",\"contentUrl\":\"https:\/\/tdcenter.org\/wp-content\/litespeed\/avatar\/d8f3b20c902e8bb3923b20886148cd59.jpg?ver=1788347320\",\"caption\":\"Bohdana Batsko\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Latin American Students Complete Their Internship at TDC","description":"Eight students from Argentina, Chile and Peru completed a remote TDC internship focused on regional perspectives and Ukraine\u2013Latin America relations.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tdcenter.org\/it\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/","og_locale":"it_IT","og_type":"article","og_title":"Latin American Students Complete Their Internship at TDC","og_description":"Eight students from Argentina, Chile and Peru completed a remote TDC internship focused on regional perspectives and Ukraine\u2013Latin America relations.","og_url":"https:\/\/tdcenter.org\/it\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/","og_site_name":"Transatlantic Dialogue Center","article_publisher":"https:\/\/www.facebook.com\/Transatlantic-Dialogue-Center-105645698740463","article_published_time":"2025-12-12T14:36:24+00:00","article_modified_time":"2026-07-04T09:02:02+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png","type":"image\/png"}],"author":"Bohdana Batsko","twitter_card":"summary_large_image","twitter_title":"Latin American Students Complete Their Internship at TDC","twitter_description":"Eight students from Argentina, Chile and Peru completed a remote TDC internship focused on regional perspectives and Ukraine\u2013Latin America relations.","twitter_misc":{"Written by":"Bohdana Batsko","Est. reading time":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#article","isPartOf":{"@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/"},"author":{"name":"Bohdana Batsko","@id":"https:\/\/tdcenter.org\/#\/schema\/person\/bfca4e53cbe272b2feb293444dfe9b55"},"headline":"A New Generation of Regional Voices: Latin American Students Complete Their Internship at TDC","datePublished":"2025-12-12T14:36:24+00:00","dateModified":"2026-07-04T09:02:02+00:00","mainEntityOfPage":{"@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/"},"wordCount":605,"commentCount":0,"publisher":{"@id":"https:\/\/tdcenter.org\/#organization"},"image":{"@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#primaryimage"},"thumbnailUrl":"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png","articleSection":["Events","Events-Spain and Latin America Cooperation Program"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/","url":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/","name":"Latin American Students Complete Their Internship at TDC","isPartOf":{"@id":"https:\/\/tdcenter.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#primaryimage"},"image":{"@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#primaryimage"},"thumbnailUrl":"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png","datePublished":"2025-12-12T14:36:24+00:00","dateModified":"2026-07-04T09:02:02+00:00","description":"Eight students from Argentina, Chile and Peru completed a remote TDC internship focused on regional perspectives and Ukraine\u2013Latin America relations.","breadcrumb":{"@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#primaryimage","url":"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png","contentUrl":"https:\/\/tdcenter.org\/wp-content\/uploads\/2025\/12\/Untitled-design.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/tdcenter.org\/2025\/12\/12\/a-new-generation-of-regional-voices-latin-american-students-complete-their-internship-at-tdc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tdcenter.org\/"},{"@type":"ListItem","position":2,"name":"A New Generation of Regional Voices: Latin American Students Complete Their Internship at TDC"}]},{"@type":"WebSite","@id":"https:\/\/tdcenter.org\/#website","url":"https:\/\/tdcenter.org\/","name":"Centro per il Dialogo Transatlantico","description":"Promoting International Peace and Security","publisher":{"@id":"https:\/\/tdcenter.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tdcenter.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tdcenter.org\/#organization","name":"Centro per il Dialogo Transatlantico","url":"https:\/\/tdcenter.org\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tdcenter.org\/#\/schema\/logo\/image\/","url":"https:\/\/tdcenter.org\/wp-content\/uploads\/2022\/04\/google.png","contentUrl":"https:\/\/tdcenter.org\/wp-content\/uploads\/2022\/04\/google.png","width":2568,"height":2487,"caption":"Transatlantic Dialogue Center"},"image":{"@id":"https:\/\/tdcenter.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Transatlantic-Dialogue-Center-105645698740463","https:\/\/www.youtube.com\/channel\/UCpJuhU4JBfpv_jsldNOc5LA"]},{"@type":"Person","@id":"https:\/\/tdcenter.org\/#\/schema\/person\/bfca4e53cbe272b2feb293444dfe9b55","name":"Bohdana Batsko","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tdcenter.org\/#\/schema\/person\/image\/","url":"https:\/\/tdcenter.org\/wp-content\/litespeed\/avatar\/d8f3b20c902e8bb3923b20886148cd59.jpg?ver=1788347320","contentUrl":"https:\/\/tdcenter.org\/wp-content\/litespeed\/avatar\/d8f3b20c902e8bb3923b20886148cd59.jpg?ver=1788347320","caption":"Bohdana Batsko"}}]}},"mfb_rest_fields":["title","yoast_head","yoast_head_json","gutenberg_elementor_mode"],"_links":{"self":[{"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/posts\/33338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/comments?post=33338"}],"version-history":[{"count":15,"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/posts\/33338\/revisions"}],"predecessor-version":[{"id":37468,"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/posts\/33338\/revisions\/37468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/media\/33340"}],"wp:attachment":[{"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/media?parent=33338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/categories?post=33338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/tags?post=33338"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/tdcenter.org\/it\/wp-json\/wp\/v2\/topic?post=33338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}