{"id":22395,"date":"2024-02-16T16:16:07","date_gmt":"2024-02-16T14:16:07","guid":{"rendered":"https:\/\/tdcenter.org\/?p=22395"},"modified":"2026-07-04T12:01:18","modified_gmt":"2026-07-04T09:01:18","slug":"peking-auf-der-internationalen-buhne-reformer-oder-revolutionar","status":"publish","type":"post","link":"https:\/\/tdcenter.org\/de\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/","title":{"rendered":"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?"},"content":{"rendered":"<div class=\"wp-block-quick-download-button-download-button aligncenter qdbn-wrapper\"><div class=\"qdbn\" data-plugin-name=\"qdbn\" data-style=\"small\" data-file=\"hide-file\" data-size=\"hide-size\"><div class=\"qdbn-download-button-inner\"><button type=\"button\" data-button-type=\"small\" class=\"g-btn f-l\" style=\"background-color:#0e107b;color:#ffffff;border-radius:25px;border:1px solid #e2e2e2\" data-attachment-id=\"40593\" data-page-id=\"18850\" data-post-id=\"\" data-have-external=\"false\" data-external-url=\"\" data-wait-duration=\"0\" data-target-blank=\"true\" data-msg=\"Please wait...\" data-member=\"0\" data-has-icon-dark=\"false\" title=\"PDF herunterladen\"><span class=\"download-btn-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 24 24\" width=\"22\" height=\"22\" aria-hidden=\"true\"><path d=\"M18 11.3l-1-1.1-4 4V3h-1.5v11.3L7 10.2l-1 1.1 6.2 5.8 5.8-5.8zm.5 3.7v3.5h-13V15H4v5h16v-5h-1.5z\"><\/path><\/svg><\/span><span>PDF herunterladen<\/span><\/button><p class=\"up\" style=\"background:transparent;border-radius:0\"><i class=\"fi fi-pdf\"><\/i><\/p><p class=\"down\" style=\"background:transparent;border-radius:0\"><i class=\"fi-folder-o\"><\/i><span class=\"file-size\">1 MB<\/span><\/p><\/div><\/div><quick-download-button-info class=\"qdb-btn-info\"><\/quick-download-button-info><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-wichtigste-schlussfolgerungen\">Wichtigste Schlussfolgerungen<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><strong>Pekings Strategie der Weltordnungspolitik<\/strong><\/strong>: Der Artikel untersucht Chinas Haltung zur globalen Politikgestaltung und seine Bereitschaft, den Status quo zu ver\u00e4ndern. Au\u00dferdem wird untersucht, welche Absichten China innerhalb des internationalen Systems verfolgt, ob es dieses reformieren oder v\u00f6llig umgestalten will.<\/li>\n\n\n\n<li><strong><strong>Appell an den Globalen S\u00fcden<\/strong><\/strong>: Der Artikel er\u00f6rtert Chinas Strategie, aus der Unzufriedenheit der L\u00e4nder des Globalen S\u00fcdens mit dem Westen zu profitieren. Peking bietet diesen L\u00e4ndern eine Alternative zum westlichen Wirtschaftsmodell und definiert damit globale Werte neu und schafft neue Institutionen.<\/li>\n\n\n\n<li><strong><strong>Zukunftsf\u00e4higkeit des chinesischen Modells<\/strong><\/strong>: Chinas Entwicklungsmodell, das durch eine starke staatliche Kontrolle strategischer Industrien und eine minimale politische Liberalisierung gekennzeichnet ist, stellt eine lebensf\u00e4hige Alternative zum westlichen Modell dar. Dieses Modell hat gezeigt, dass wirtschaftlicher Fortschritt m\u00f6glich ist, ohne sich liberalen politischen Normen anzupassen. Allerdings werden Bedenken ge\u00e4u\u00dfert, ob das chinesische Modell angesichts der einzigartigen demografischen und wirtschaftlichen Gegebenheiten des Landes universell anwendbar und langfristig lebensf\u00e4hig ist.<\/li>\n\n\n\n<li><strong><strong>Chinas Beteiligung an internationalen Institutionen<\/strong><\/strong>: Der Artikel befasst sich mit Chinas zunehmender Beteiligung an globalen Institutionen und seinen Bem\u00fchungen, neue Institutionen wie die AIIB und die BRICS-Bank zu gr\u00fcnden, was eher auf eine Strategie der vorsichtigen Reformen als auf eine Revolution hindeutet.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"354\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-5-1024x354.png\" alt=\"Cover image for: Beijing on International Arena \u2013 Reformer or Revolutionary?\" class=\"wp-image-21816\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-5-1024x354.png 1024w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-5-600x207.png 600w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-5-768x265.png 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-5-18x6.png 18w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-5.png 1244w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">In den letzten zehn Jahren wurde die von den westlichen M\u00e4chten gef\u00fchrte liberale Weltordnung von neu entstehenden autorit\u00e4ren Regimen gef\u00e4hrdet, von denen China das einflussreichste ist. Der rasche Aufstieg der Volksrepublik China von einem nicht anerkannten Land zu einer Gro\u00dfmacht auf der internationalen B\u00fchne hat weniger als ein Jahrhundert gedauert und die ganze Welt \u00fcberrascht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vor kurzem hat die VR China ihre wirtschaftliche St\u00e4rke genutzt, um in den \u201eelit\u00e4ren Club\u201c der f\u00fchrenden L\u00e4nder einzutreten. Als Gro\u00dfmacht will China eine attraktive Alternative zum westlichen Wirtschaftsmodell bieten, das auf Demokratie, Transparenz und liberalen Werten beruht. Es nutzt die Unzufriedenheit der L\u00e4nder des Globalen S\u00fcdens mit dem Westen aus, um die Werte, die der liberalen Weltordnung zu Grunde liegen, neu zu definieren und neue Institutionen f\u00fcr die L\u00e4nder zu schaffen, deren Stimmen unbeachtet geblieben sind. Diese Faktoren werfen f\u00fcr die Welt eine beunruhigende Frage auf: Will China die Weltordnung reformieren oder eine neue autorit\u00e4re Ordnung errichten?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Artikel untersucht die wichtigsten Merkmale der von den USA dominierten liberalen Weltordnung, den damit verbundenen Herausforderungen und die Rolle, die China innerhalb (oder au\u00dferhalb) dieses Systems zu spielen bereit ist. Au\u00dferdem wird er\u00f6rtert, welche Bedenken Peking gegen\u00fcber dem derzeitigen globalen Regierungssystem hegt und ob die VR China bereit ist, radikale Schritte zu unternehmen, um es zu st\u00fcrzen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-versagt-die-liberale-weltordnung\"><strong>Versagt die liberale Weltordnung?<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dem Ende des Zweiten Weltkriegs gelang es den USA schlie\u00dflich, eine liberale Weltordnung aufzubauen \u2014 ein System, das auf Normen, Institutionen, Rechtsstaatlichkeit und liberalen Werten beruht. Nach dem Zusammenbruch der Sowjetunion waren die USA die einzige Supermacht und hatten die M\u00f6glichkeit, ihren Einfluss und ihre Werte auf die ganze Welt auszudehnen. Im Moment des ideologischen Sieges schien die Zukunft positiv und hell zu sein: Francis Fukuyama erkl\u00e4rte sogar, dies sei das Ende der Geschichte \u2014 der Triumph der liberalen Werte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend die USA und ihre Verb\u00fcndeten ihren Sieg im Kalten Krieg feierten, traten neue M\u00e4chte auf den Plan, die bereit waren, die triumphale Weltordnung zu untergraben. China und Russland waren zwei autorit\u00e4re M\u00e4chte, die ihren Platz unter den f\u00fchrenden L\u00e4ndern der Welt einnehmen wollten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heute, im Jahr 2023, f\u00e4llt es schwer, sich diese von den westlichen Staats- und Regierungschefs angestrebte strahlende Zukunft vorzustellen. Die Welt hat zwei verheerende Wirtschaftskrisen, einen Anstieg des Populismus, die Missachtung der Menschenrechte, Terrorismus und neue milit\u00e4rische Konflikte erlebt. Die EU wird durch Erosion der Demokratie und Backlash-Politik ersch\u00fcttert, Japan versucht, China aufzuhalten, und selbst die USA, die S\u00e4ule des Systems, haben einmal einen Pr\u00e4sidenten gew\u00e4hlt, dessen Ansichten den meisten der erkl\u00e4rten liberalen Werte widersprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um die liberale Weltordnung aufrechtzuerhalten, mussten die westlichen Demokratien manchmal auf nicht-liberale Mittel der Abschreckung und Konfliktl\u00f6sung zur\u00fcckgreifen, was ihnen den Ruf der Heuchelei einbrachte. Die Tatsache, dass selbst westliche M\u00e4chte, die die Normen und Institutionen geschaffen haben, sich nicht an sie halten, erm\u00f6glichte es autorit\u00e4ren M\u00e4chten, diese Kontroverse zu manipulieren: Sie rechtfertigen damit Verst\u00f6\u00dfe gegen die in der liberalen Weltordnung festgelegten Normen und Regeln. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die russische Invasion in der Ukraine im Jahr 2022 war ein deutliches Zeichen daf\u00fcr, dass Moskau plant, die liberale Weltordnung zu st\u00fcrzen, und stellte die geschw\u00e4chten Demokratien des Westens vor noch gr\u00f6\u00dfere Herausforderungen. Diese Wendung der Ereignisse hat eine weitere wichtige Debatte ausgel\u00f6st, n\u00e4mlich die Frage, welche Ziele China innerhalb des internationalen Systems verfolgt und wie weit Peking bereit ist zu gehen, um sie zu erreichen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-das-chinesische-modell-wirtschaftswachstum-ohne-politische-liberalisierung\"><strong>Das \u201echinesische Modell&#8221; \u2014 Wirtschaftswachstum ohne politische Liberalisierung<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Die Volksrepublik China ist sehr stolz auf das, was sie als \u201efriedlichen Aufstieg\u201c bezeichnet: keine Kriege, keine Einmischung in die Angelegenheiten anderer L\u00e4nder. Ob er wirklich so friedlich war, wie die Chinesen behaupten, l\u00e4sst sich dar\u00fcber streiten, aber eines ist klar: Der \u201eAufstieg\u201c hat stattgefunden, und er hat die ganze Welt ersch\u00fcttert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In den letzten Jahrzehnten hat die VR China einen rasanten wirtschaftlichen Aufschwung erlebt \u2014 eine Entwicklung, die westliche M\u00e4chte erst nach mehreren Jahrhunderten geschafft haben. Als die Volksrepublik China 1949 gegr\u00fcndet wurde, war sie ein vom Krieg zerrissenes Land mit einer extrem armen Bev\u00f6lkerung und ohne Zukunftsperspektiven \u2014 sie galt nicht als legitimer Nachfolger des Kaiserreichs China und wurde von allen internationalen Institutionen ausgeschlossen. Damals, vor 70 Jahren, konnte niemand erwarten, dass die VR China im Jahr 2010 Japan \u00fcbertreffen und die zweitgr\u00f6\u00dfte Volkswirtschaft der Welt werden w\u00fcrde. Die chinesischen Beamten gingen bei den sozialen Wirtschaftsreformen klug und strategisch vor und waren so in der Lage, die Vorteile der von den USA gef\u00fchrten Weltordnung zu ihrem Vorteil zu nutzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der chinesische Professfor Zhang Weiwei behauptet, dass China in nur 40 Jahren vier industrielle Revolutionen erlebt hat \u2014 beginnend mit den Reformen von Deng Xiaoping, der China f\u00fcr die Welt \u201e\u00f6ffnete\u201c. In diesen 40 Jahren hat sich die Lebensqualit\u00e4t der chinesischen B\u00fcrger erstaunlich verbessert: Einst lebten sie in einem armen Agrarland, und heute genie\u00dfen sie Hightech-St\u00e4dte, 5G-Internet, Hochgeschwindigkeitsz\u00fcge und st\u00e4ndige wissenschaftliche Fortschritte. Dieser rasche Aufstieg verschaffte der KPCh die unersch\u00fctterliche Unterst\u00fctzung ihrer Bev\u00f6lkerung und erm\u00f6glichte es der VR China, zu einem der wichtigsten Akteure auf der internationalen B\u00fchne zu werden.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"471\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-6-1024x471.png\" alt=\"Cover image for: Beijing on International Arena \u2013 Reformer or Revolutionary?\" class=\"wp-image-21817\" style=\"width:650px;height:auto\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-6-1024x471.png 1024w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-6-600x276.png 600w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-6-768x353.png 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-6-18x8.png 18w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-6.png 1048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Mit dem Wachstum der chinesischen Wirtschaft stiegen auch ihre Ambitionen. In Anbetracht ihrer Errungenschaften und der neu gewonnenen Macht in der Weltpolitik erkannte die KPCh, dass sie nicht mehr nach den Regeln des Westens spielen musste. Stattdessen konnte sie ein alternatives Modell der wirtschaftlichen Entwicklung anbieten. Das oft als \u201echinesische Modell\u201c bezeichnete System dient als Beispiel daf\u00fcr, dass ein erfolgreicher wirtschaftlicher Aufstieg keine politische Liberalisierung erfordert. Die Hauptmerkmale dieses Modells sind eine exportorientierte Wirtschaft mit starker staatlicher Intervention, pragmatische Reformen und die Abh\u00e4ngigkeit von ausl\u00e4ndischen Investitionen. Alle strategischen Industriezweige der chinesischen Wirtschaft werden von staatlichen Unternehmen kontrolliert, was dem Staat eine absolute Dominanz im Wirtschaftssektor erm\u00f6glicht. Zusammen mit der unbestrittenen Macht der KPCh wird dies als Quelle der Stabilit\u00e4t angesehen, die f\u00fcr eine erfolgreiche Entwicklung entscheidend sein soll. China sieht den st\u00e4ndigen Machtwechsel und die politische Liberalisierung in den westlichen Demokratien als deren Schw\u00e4che an, was zu verschiedenen Krisen f\u00fchrt, die den Fortschritt des Landes bremsen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-warum-ist-das-chinesische-modell-so-attraktiv\"><strong><strong>Warum ist das chinesische Modell so attraktiv<\/strong>?<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">China hat bewiesen, dass Autoritarismus nicht das Gegenteil von Modernit\u00e4t ist \u2014 diese beiden Merkmale widersprechen sich nicht, sondern k\u00f6nnen gleichzeitig existieren und gedeihen. Diese Idee ist bei den Politikern der Entwicklungsl\u00e4nder, denen es schwer f\u00e4llt, alle Liberalisierungs- und Demokratisierungsanforderungen der westlichen Welt zu erf\u00fcllen, \u00e4u\u00dferst beliebt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Entwicklungsl\u00e4nder sind immer auf der Suche nach Investitionen und finanzieller Unterst\u00fctzung. Eine M\u00f6glichkeit, diese zu erhalten, ist die Zusammenarbeit mit dem IWF, der Weltbank, der Europ\u00e4ischen Investitionsbank oder anderen vom Westen gef\u00fchrten Institutionen, deren Darlehen immer an Bedingungen gekn\u00fcpft sind und Reformen erfordern. Und obwohl diese Bedingungen dazu gedacht sind, die wirtschaftliche Entwicklung eines kreditnehmenden Landes zu f\u00f6rdern, werden sie oft zu einer schweren Belastung f\u00fcr die Regierung. Hinzu kommt, dass nicht alle Entwicklungsl\u00e4nder die liberale Weltordnung und das westlich gef\u00fchrte System attraktiv finden: Sie sind nicht bereit, sich zu Wahldemokratien zu entwickeln, die Menschenrechte zu sch\u00fctzen und sich an die Rechtsstaatlichkeit zu halten. Dadurch entsteht ein Interessenkonflikt, der dazu f\u00fchrt, dass nach anderen Wegen gesucht wird, um sich wirtschaftlich zu entwickeln und Kredite zu erhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Anbetracht dieser Situation scheint das \u201echinesische Modell\u201c die perfekte Antwort zu sein. Die chinesischen Politiker behaupten, dass sie nicht vorhaben, explizit den \u201eSozialismus mit chinesischen Merkmalen\u201c in andere L\u00e4nder zu exportieren, aber sie glauben, ein Beispiel f\u00fcr ein Wirtschaftsmodell gegeben zu haben, das Entwicklung gew\u00e4hrleistet und gleichzeitig keine drastischen liberalen Reformen erfordert. Dar\u00fcber hinaus ist die VR China im Rahmen der Neuen Seidenstra\u00dfe (Belt and Road Initiative, BRI) bereit, in Entwicklungsl\u00e4nder zu investieren und mit ihnen bei Infrastrukturprojekten zusammenzuarbeiten. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Lander-BRI-1024x576.png\" alt=\"\" class=\"wp-image-22397\" style=\"width:689px;height:auto\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Lander-BRI-1024x576.png 1024w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Lander-BRI-600x338.png 600w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Lander-BRI-768x432.png 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Lander-BRI-18x10.png 18w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Lander-BRI.png 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">China behauptet auch, dass es keine Bedingungen an die Kredite kn\u00fcpft und sich im Gegensatz zu den westlichen L\u00e4ndern nicht in die Innenpolitik einmischt. In Bezug auf die Zusammenarbeit mit afrikanischen L\u00e4ndern erkl\u00e4rt die VR China beispielsweise, dass sie nach dem <a href=\"http:\/\/www.xinhuanet.com\/english\/2018-09\/06\/c_137447556.htm\">Prinzip der \u201ef\u00fcnf Nein\u201c<\/a> verf\u00e4hrt: keine Einmischung in die Entwicklungswege der einzelnen L\u00e4nder, keine Einmischung in ihre inneren Angelegenheiten, kein Aufzwingen des chinesischen Willens, keine Bindung der Hilfe an politische Bedingungen und kein Streben nach eigenn\u00fctzigen politischen Vorteilen bei Investitionen und finanzieller Zusammenarbeit. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es stimmt zwar, dass die VR China nicht versucht, ihre Ansichten \u00fcber die Regelung interner Angelegenheiten durchzusetzen, aber die Bedingungen sind nach wie vor gegeben, sie sind nur anders. China nutzt Kredite, um sich innerhalb der internationalen Institutionen Unterst\u00fctzung zu verschaffen und \u2014 langfristig gesehen \u2014 um politischen Einfluss auf L\u00e4nder zu nehmen, die nicht in der Lage sind, ihre Schulden zu begleichen oder sogar Zugang zu ihrer kritischen Infrastruktur zu erhalten. Dennoch sind die Regierungen der Entwicklungsl\u00e4nder, insbesondere derjenigen, die von korrupten autorit\u00e4ren Regimen kontrolliert werden, bereit, chinesische Investitionen zu akzeptieren und die Interessen der KPCh im Ausland zu f\u00f6rdern.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/China-BRI-1024x576.png\" alt=\"\" class=\"wp-image-22398\" style=\"width:680px;height:auto\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/China-BRI-1024x576.png 1024w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/China-BRI-600x338.png 600w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/China-BRI-768x432.png 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/China-BRI-18x10.png 18w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/China-BRI.png 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Obwohl das \u201echinesische Modell\u201c zweifellos eine gewisse Anziehungskraft hat, besteht die Sorge, dass es sich nicht auf andere Entwicklungsl\u00e4nder \u00fcbertragen l\u00e4sst, au\u00dfer auf die VR China selbst. Dank einer riesigen Bev\u00f6lkerung und qualifizierter billiger Arbeitskr\u00e4fte ist es China gelungen, viele Investoren anzuziehen und seine Exporte zu steigern \u2014 ein Vorteil, den viele kleinere Entwicklungsl\u00e4nder nicht haben. Ein weiterer entscheidender Punkt ist, dass sich die chinesische Wirtschaft zu verlangsamen beginnt und sich Herausforderungen innerhalb des Systems abzeichnen, z. B. die Immobilienkrise. Die Frage f\u00fcr die kommenden Jahre ist, ob die KPCh in der Lage sein wird, diese Schwierigkeiten zu \u00fcberwinden und die weitere Entwicklung des Landes zu gew\u00e4hrleisten. In Anbetracht dieser Faktoren w\u00e4re es f\u00fcr die Entwicklungsl\u00e4nder eine ziemlich riskante Entscheidung, das \u201echinesische Modell\u201c zu \u00fcbernehmen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-peking-reformer-oder-revolutionar\"><strong><strong>Peking \u2014 Reformer oder Revolution\u00e4r<\/strong>?<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Das moderne China verf\u00fcgt \u00fcber eine gro\u00dfe politische und wirtschaftliche Macht \u2014 eine der gr\u00f6\u00dften Fragen ist daher, was die Volksrepublik China damit zu tun plant. Wird es versuchen, die von den USA gef\u00fchrte liberale Weltordnung zu st\u00fcrzen? Oder m\u00f6chte es sie so umgestalten, dass sie seinen eigenen Interessen entspricht?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peking hat keineswegs die Absicht, die liberale Weltordnung so zu akzeptieren, wie sie jetzt besteht. Obwohl sich die chinesische F\u00fchrung nicht direkt dazu ge\u00e4u\u00dfert hat, ob die derzeitige Ordnung f\u00fcr die VR China passt, behauptet sie, an den so genannten \u201eF\u00fcnf Prinzipien der friedlichen Koexistenz\u201c festzuhalten: gegenseitige Achtung der Souver\u00e4nit\u00e4t und territorialen Integrit\u00e4t, gegenseitiger Nichtangriff, Nichteinmischung in die inneren Angelegenheiten des jeweils anderen, Gleichheit und gegenseitiger Nutzen sowie friedliche Koexistenz. Diese Werte k\u00f6nnten den Kern von Chinas idealer Weltordnung bilden und erlauben es auch, die chinesischen Bedenken gegen\u00fcber der bestehenden Ordnung zu analysieren.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"482\" height=\"481\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-10.png\" alt=\"Cover image for: Beijing on International Arena \u2013 Reformer or Revolutionary?\" class=\"wp-image-21821\" style=\"width:370px;height:auto\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-10.png 482w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-10-300x300.png 300w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-10-12x12.png 12w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><figcaption class=\"wp-element-caption\"><em>Daten von der Asia Maritime Transparency Initiative;<\/em><br><em>Design von Aliza Grant, Forbes-Mitarbeiterin<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Die Achtung der Souver\u00e4nit\u00e4t und der territorialen Integrit\u00e4t ist f\u00fcr China der wichtigste Wert, den es auf der internationalen B\u00fchne einhalten muss. Peking betrachtet die Insel Taiwan, auf der sich die Republik China befindet, als sein Territorium und ist unzufrieden mit L\u00e4ndern, die trotz der Ein-China-Politik weiterhin mit Taipeh zusammenarbeiten. Abgesehen davon betrifft die Frage der territorialen Integrit\u00e4t auch die Region Tibet sowie die von der Weltgemeinschaft umstrittenen Inselketten im S\u00fcdchinesischen Meer. In einem skandal\u00f6sen Akt der Missachtung der Rechtsstaatlichkeit hat sich China geweigert, sich an das Urteil des St\u00e4ndigen Schiedshofs von 2016 zu Gunsten der Philippinen in Bezug auf den Streit im S\u00fcdchinesischen Meer zu halten. Angesichts dieser Probleme legt Peking gro\u00dfen Wert auf die Wahrung der territorialen Integrit\u00e4t in der internationalen Arena. So hat die VR China beispielsweise die Annexion der Krim und vier ukrainischer Regionen durch Russland nie anerkannt, obwohl sie Moskaus Vorgehen auch nicht verurteilt hat. Es ist wichtig, darauf hinzuweisen, dass die VR China die Frage der Einmischung in die territoriale Integrit\u00e4t nicht so ernst nehmen w\u00fcrde, wenn sie nicht ihre eigenen strittigen Anspr\u00fcche auf Taiwan, Tibet und das S\u00fcdchinesische Meer h\u00e4tte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiterer wichtiger Grundsatz ist die Nichteinmischung in innere Angelegenheiten. Die chinesischen Beamten sind der Ansicht, dass ausl\u00e4ndische Regierungen auf keinen Fall in der Lage sein sollten, eine Einmischung in die inneren Angelegenheiten eines anderen Staates zu rechtfertigen. Dies ist f\u00fcr Peking ein dringendes Problem, insbesondere im Hinblick auf den Schutz der Menschenrechte. Die westliche liberale Weltordnung sieht vor, dass ausl\u00e4ndische M\u00e4chte im Falle von Menschenrechtsverletzungen das Recht haben, einzugreifen, um die Verbrechen zu beenden. China, ein autorit\u00e4res Land, das verschiedener Menschenrechtsverletzungen beschuldigt wird, ist mit dem Konzept der humanit\u00e4ren Intervention nicht einverstanden und w\u00fcrde mit jedem Regime zusammenarbeiten, solange es f\u00fcr das Land von Vorteil ist.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11.png\" alt=\"Cover image for: Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?\" class=\"wp-image-21822\" style=\"width:432px;height:auto\"\/><figcaption class=\"wp-element-caption\"><em>Chinas Pr\u00e4sident Xi Jinping sitzt auf dem Podium,<\/em><br><em>w\u00e4hrend die Teilnehmer das Weltwirtschaftsforum in Davos,<\/em><br><em>Schweiz, am 17. Januar verlassen. (Michel Euler\/AP)<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Au\u00dferdem sollte der Grundsatz der Gleichheit und des gegenseitigen Nutzens erw\u00e4hnt werden. Obwohl es selbstverst\u00e4ndlich und offensichtlich klingt, spiegelt es eine der grundlegenden Bedenken Chinas gegen\u00fcber der liberalen Weltordnung wider: Peking glaubt nicht, dass sie von Gleichheit gepr\u00e4gt ist. Die VR China behauptet, dass die Institutionen und Normen, die den Kern der liberalen Weltordnung bilden, den westlichen M\u00e4chten zum Vorteil dienen (z. B. haben die USA de facto ein Vetorecht im IWF).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um die oben genannten Probleme zu bew\u00e4ltigen, beteiligt sich China immer st\u00e4rker an internationalen Institutionen und mischt sich in das Weltgeschehen ein. Peking nutzt die UNO und ihre Institutionen aktiv, um sich als eine der f\u00fchrenden Nationen der Welt zu etablieren. Gegenw\u00e4rtig geh\u00f6rt die VR China zu den L\u00e4ndern, die die meisten Friedenssoldaten f\u00fcr die UN-Friedensmissionen bereitstellen, und \u00fcbertrifft damit alle anderen Mitglieder des UN-Sicherheitsrats. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine weitere bemerkenswerte Ma\u00dfnahme, die China im Rahmen der gegenw\u00e4rtigen Weltordnung ergreift, ist die Schaffung neuer oder die St\u00e4rkung bestehender Institutionen, die den Interessen Pekings dienen. Die Schanghaier Organisation f\u00fcr Zusammenarbeit (SOZ), die Asiatische Infrastrukturinvestmentbank (AIIB) und die BRICS-Bank werden als Alternativen zu den westlich gef\u00fchrten Institutionen vorgestellt. Bemerkenswerterweise hat sich die 2016 gegr\u00fcndete AIIB bereits zu einer m\u00e4chtigeren Finanzinstitution entwickelt als die vom Westen gegr\u00fcndete Asiatische Entwicklungsbank. Durch die Schaffung dieser Institutionen hofft China, sich als F\u00fchrungsmacht des globalen S\u00fcdens und als F\u00fcrsprecher der Interessen der Entwicklungsl\u00e4nder zu pr\u00e4sentieren.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Einstellung-gegenuber-China-1024x576.png\" alt=\"\" class=\"wp-image-22399\" style=\"width:688px;height:auto\" srcset=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Einstellung-gegenuber-China-1024x576.png 1024w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Einstellung-gegenuber-China-600x338.png 600w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Einstellung-gegenuber-China-768x432.png 768w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Einstellung-gegenuber-China-18x10.png 18w, https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/02\/Einstellung-gegenuber-China.png 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Unter Ber\u00fccksichtigung der oben genannten Faktoren gibt es keine ausreichenden Beweise f\u00fcr die Behauptung, dass China zu einem Revolution\u00e4r wird. Obwohl Peking versucht, einige der liberalen Werte neu zu definieren und alternative internationale Institutionen zu schaffen, stimmen seine Prinzipien immer noch gr\u00f6\u00dftenteils mit den westlichen \u00fcberein, es f\u00f6rdert die Zusammenarbeit innerhalb der von den westlichen M\u00e4chten geschaffenen Institutionen, sucht nach Verb\u00fcndeten und Unterst\u00fctzung innerhalb dieser Institutionen (z. B. mit Hilfe der BRI) und zeigt kein gro\u00dfes Interesse daran, die bestehende Ordnung zu untergraben. China profitiert von einer globalisierten Welt, dem freien Handel und der Zusammenarbeit mit seinen westlichen Partnern, und es w\u00e4re f\u00fcr die VR China also nicht von Vorteil, die bestehende Weltordnung vollst\u00e4ndig zu st\u00fcrzen. Was man beobachten kann, ist, dass Peking versucht, einige der strukturellen Elemente der liberalen Welt so anzupassen, dass sie seinen Interessen besser dienen, und dass es eine F\u00fchrungsrolle innerhalb des globalen S\u00fcdens anstrebt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-schlussfolgerung\"><strong><strong>Schlussfolgerung<\/strong><\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Der rasante Aufstieg Chinas und die Herausforderungen, vor denen die liberale Weltordnung im 21. Jahrhundert steht, haben Debatten \u00fcber die Zukunft der globalen Institutionen ausgel\u00f6st. China nutzt sein beispielloses Wirtschaftswachstum, um ein alternatives Entwicklungsmodell zu f\u00f6rdern, das keine politische Liberalisierung vorsieht. Auf diese Weise k\u00f6nnen die Entwicklungsl\u00e4nder der Notwendigkeit entgehen, belastende Bedingungen zu erf\u00fcllen, die von westlich gef\u00fchrten Institutionen auferlegt werden. Das &#8220;chinesische Modell&#8221; stellt einen autorit\u00e4ren Ansatz f\u00fcr wirtschaftlichen Fortschritt dar und stellt das traditionelle westliche Narrativ in Frage, dass politische Liberalisierung eine Voraussetzung f\u00fcr Modernisierung ist. Obwohl es bis zu einem gewissen Grad attraktiv ist, existiert es noch nicht lange genug, um seine Wirksamkeit auf lange Sicht zu beweisen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend China seinen Einfluss durch die Schaffung neuer Institutionen und Projekte wie die Belt and Road Initiative weiter ausbaut, machen sich westliche Politiker immer mehr Sorgen \u00fcber Pekings Absichten. China lehnt die liberalen Werte, die den Kern des modernen internationalen Systems bilden, offen ab und vertritt seine eigene Auffassung von den Grunds\u00e4tzen, die die Grundlage der globalen Ordnung bilden sollten. Gleichzeitig bef\u00fcrwortet China die Zusammenarbeit im Rahmen der UNO und ist nicht bereit, auf die Vorteile des globalisierten und multilateralen Systems zu verzichten. Gegenw\u00e4rtig kann China kaum als Revolution\u00e4r angesehen werden, der versucht, die bestehende Weltordnung als Ganzes zu untergraben und eine v\u00f6llig neue aufzubauen. Die VR China ist eher eine Kraft, die darauf abzielt, das internationale System an ihre Bed\u00fcrfnisse anzupassen. Die Frage, ob Pekings Ambitionen und Durchsetzungsf\u00e4higkeit in Zukunft zunehmen oder gleich bleiben werden, bleibt offen. Aber wenn die westlichen M\u00e4chte ihre liberale Ordnung stabil und unver\u00e4ndert sehen wollen, m\u00fcssen sie sich in ihrer Politik zur Eind\u00e4mmung Chinas einig sein.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Disclaimer: Die Ansichten, Gedanken und Meinungen, die in den auf dieser Website ver\u00f6ffentlichten Artikeln zum Ausdruck gebracht werden, sind ausschlie\u00dflich die der Autoren und nicht unbedingt die des Transatlantic Dialogue Center, seiner Aussch\u00fcsse oder seiner Partnerorganisationen. Die Artikel sollen den Dialog und die Diskussion f\u00f6rdern und stellen keine offiziellen politischen Positionen des Transatlantic Dialogue Center oder anderer Organisationen dar, mit denen die Autoren m\u00f6glicherweise verbunden sind.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Wichtigste Schlussfolgerungen In den letzten zehn Jahren wurde die von den westlichen M\u00e4chten gef\u00fchrte liberale Weltordnung von neu entstehenden autorit\u00e4ren Regimen gef\u00e4hrdet, von denen China das einflussreichste ist. Der rasche Aufstieg der Volksrepublik China von einem nicht anerkannten Land zu einer Gro\u00dfmacht auf der internationalen B\u00fchne hat weniger als ein Jahrhundert gedauert und die ganze [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":21822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65,31],"tags":[],"topic":[85,90,93],"class_list":["post-22395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia-ger-analyses","category-ger-analyses","topic-china","topic-economy","topic-geopolitics"],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r? - Transatlantic Dialogue Center<\/title>\n<meta name=\"description\" content=\"China fordert die globale Governance heraus, indem es Alternativen zu westlichen Modellen anbietet und seine Rolle in globalen Institutionen st\u00e4rkt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tdcenter.org\/de\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?\" \/>\n<meta property=\"og:description\" content=\"Transatlantic Dialogue Center (TDC) is a non-governmental and non-partisan think tank that provides high-quality policy advice to private and public clients. The network of our friends and partners includes government officials, members of parliaments, businessmen, journalists, experts and analysts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tdcenter.org\/de\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/\" \/>\n<meta property=\"og:site_name\" content=\"Transatlantic Dialogue Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Transatlantic-Dialogue-Center-105645698740463\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-16T14:16:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-04T09:01:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png\" \/>\n\t<meta property=\"og:image:width\" content=\"479\" \/>\n\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Stepan Rusyn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stepan Rusyn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/\"},\"author\":{\"name\":\"Stepan Rusyn\",\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/person\/10d9eb6be418ce623b4525c0dedbadfa\"},\"headline\":\"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?\",\"datePublished\":\"2024-02-16T14:16:07+00:00\",\"dateModified\":\"2026-07-04T09:01:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/\"},\"wordCount\":3176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/tdcenter.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png\",\"articleSection\":[\"Asia\",\"German Analyses\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/\",\"url\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/\",\"name\":\"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r? - Transatlantic Dialogue Center\",\"isPartOf\":{\"@id\":\"https:\/\/tdcenter.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png\",\"datePublished\":\"2024-02-16T14:16:07+00:00\",\"dateModified\":\"2026-07-04T09:01:18+00:00\",\"description\":\"China fordert die globale Governance heraus, indem es Alternativen zu westlichen Modellen anbietet und seine Rolle in globalen Institutionen st\u00e4rkt.\",\"breadcrumb\":{\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#primaryimage\",\"url\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png\",\"contentUrl\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png\",\"width\":479,\"height\":213,\"caption\":\"Cover image for: Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tdcenter.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tdcenter.org\/#website\",\"url\":\"https:\/\/tdcenter.org\/\",\"name\":\"Transatlantic Dialogue Center\",\"description\":\"Promoting International Peace and Security\",\"publisher\":{\"@id\":\"https:\/\/tdcenter.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tdcenter.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tdcenter.org\/#organization\",\"name\":\"Transatlantic Dialogue Center\",\"url\":\"https:\/\/tdcenter.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2022\/04\/google.png\",\"contentUrl\":\"https:\/\/tdcenter.org\/wp-content\/uploads\/2022\/04\/google.png\",\"width\":2568,\"height\":2487,\"caption\":\"Transatlantic Dialogue Center\"},\"image\":{\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Transatlantic-Dialogue-Center-105645698740463\",\"https:\/\/www.youtube.com\/channel\/UCpJuhU4JBfpv_jsldNOc5LA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/person\/10d9eb6be418ce623b4525c0dedbadfa\",\"name\":\"Stepan Rusyn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/tdcenter.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/tdcenter.org\/wp-content\/litespeed\/avatar\/933c2b7a4204b3771069324be5fa5a24.jpg?ver=1784114173\",\"contentUrl\":\"https:\/\/tdcenter.org\/wp-content\/litespeed\/avatar\/933c2b7a4204b3771069324be5fa5a24.jpg?ver=1784114173\",\"caption\":\"Stepan Rusyn\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r? - Transatlantic Dialogue Center","description":"China fordert die globale Governance heraus, indem es Alternativen zu westlichen Modellen anbietet und seine Rolle in globalen Institutionen st\u00e4rkt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tdcenter.org\/de\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/","og_locale":"de_DE","og_type":"article","og_title":"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?","og_description":"Transatlantic Dialogue Center (TDC) is a non-governmental and non-partisan think tank that provides high-quality policy advice to private and public clients. The network of our friends and partners includes government officials, members of parliaments, businessmen, journalists, experts and analysts.","og_url":"https:\/\/tdcenter.org\/de\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/","og_site_name":"Transatlantic Dialogue Center","article_publisher":"https:\/\/www.facebook.com\/Transatlantic-Dialogue-Center-105645698740463","article_published_time":"2024-02-16T14:16:07+00:00","article_modified_time":"2026-07-04T09:01:18+00:00","og_image":[{"width":479,"height":213,"url":"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png","type":"image\/png"}],"author":"Stepan Rusyn","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Stepan Rusyn","Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#article","isPartOf":{"@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/"},"author":{"name":"Stepan Rusyn","@id":"https:\/\/tdcenter.org\/#\/schema\/person\/10d9eb6be418ce623b4525c0dedbadfa"},"headline":"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?","datePublished":"2024-02-16T14:16:07+00:00","dateModified":"2026-07-04T09:01:18+00:00","mainEntityOfPage":{"@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/"},"wordCount":3176,"commentCount":0,"publisher":{"@id":"https:\/\/tdcenter.org\/#organization"},"image":{"@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#primaryimage"},"thumbnailUrl":"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png","articleSection":["Asia","German Analyses"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/","url":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/","name":"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r? - Transatlantic Dialogue Center","isPartOf":{"@id":"https:\/\/tdcenter.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#primaryimage"},"image":{"@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#primaryimage"},"thumbnailUrl":"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png","datePublished":"2024-02-16T14:16:07+00:00","dateModified":"2026-07-04T09:01:18+00:00","description":"China fordert die globale Governance heraus, indem es Alternativen zu westlichen Modellen anbietet und seine Rolle in globalen Institutionen st\u00e4rkt.","breadcrumb":{"@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#primaryimage","url":"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png","contentUrl":"https:\/\/tdcenter.org\/wp-content\/uploads\/2024\/01\/image-11-e1754132834733.png","width":479,"height":213,"caption":"Cover image for: Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?"},{"@type":"BreadcrumbList","@id":"https:\/\/tdcenter.org\/2024\/02\/16\/peking-auf-der-internationalen-buhne-reformer-oder-revolutionar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tdcenter.org\/"},{"@type":"ListItem","position":2,"name":"Peking auf der internationalen B\u00fchne \u2014Reformer oder Revolution\u00e4r?"}]},{"@type":"WebSite","@id":"https:\/\/tdcenter.org\/#website","url":"https:\/\/tdcenter.org\/","name":"Transatlantic Dialogue Center","description":"F\u00f6rderung des internationalen Friedens und der Sicherheit","publisher":{"@id":"https:\/\/tdcenter.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tdcenter.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tdcenter.org\/#organization","name":"Transatlantic Dialogue Center","url":"https:\/\/tdcenter.org\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tdcenter.org\/#\/schema\/logo\/image\/","url":"https:\/\/tdcenter.org\/wp-content\/uploads\/2022\/04\/google.png","contentUrl":"https:\/\/tdcenter.org\/wp-content\/uploads\/2022\/04\/google.png","width":2568,"height":2487,"caption":"Transatlantic Dialogue Center"},"image":{"@id":"https:\/\/tdcenter.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Transatlantic-Dialogue-Center-105645698740463","https:\/\/www.youtube.com\/channel\/UCpJuhU4JBfpv_jsldNOc5LA"]},{"@type":"Person","@id":"https:\/\/tdcenter.org\/#\/schema\/person\/10d9eb6be418ce623b4525c0dedbadfa","name":"Stepan Rusyn","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tdcenter.org\/#\/schema\/person\/image\/","url":"https:\/\/tdcenter.org\/wp-content\/litespeed\/avatar\/933c2b7a4204b3771069324be5fa5a24.jpg?ver=1784114173","contentUrl":"https:\/\/tdcenter.org\/wp-content\/litespeed\/avatar\/933c2b7a4204b3771069324be5fa5a24.jpg?ver=1784114173","caption":"Stepan Rusyn"}}]}},"mfb_rest_fields":["title","yoast_head","yoast_head_json","gutenberg_elementor_mode"],"_links":{"self":[{"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/posts\/22395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/comments?post=22395"}],"version-history":[{"count":3,"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/posts\/22395\/revisions"}],"predecessor-version":[{"id":37399,"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/posts\/22395\/revisions\/37399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/media\/21822"}],"wp:attachment":[{"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/media?parent=22395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/categories?post=22395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/tags?post=22395"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/tdcenter.org\/de\/wp-json\/wp\/v2\/topic?post=22395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}